{"id":6937,"date":"2025-02-04T07:16:17","date_gmt":"2025-02-04T07:16:17","guid":{"rendered":"https:\/\/nuevo-renacer.com\/?page_id=6937"},"modified":"2025-02-04T08:01:18","modified_gmt":"2025-02-04T08:01:18","slug":"las-ciudades-espirituales","status":"publish","type":"page","link":"https:\/\/nuevo-renacer.com\/it\/las-ciudades-espirituales\/","title":{"rendered":"Las ciudades espirituales"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-2657272e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-128129bfd533c81c04b39f4d33705785 wp-block-paragraph\"><strong>Las ciudades espirituales<\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6daf5027 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"550\" height=\"392\" src=\"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2025\/02\/nosso-lar.jpeg\" alt=\"\" class=\"wp-image-6938\" srcset=\"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2025\/02\/nosso-lar.jpeg 550w, https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2025\/02\/nosso-lar-300x214.jpeg 300w, https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2025\/02\/nosso-lar-18x12.jpeg 18w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4a400fca alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-afc1eb572a3db51699654d371cc54837 wp-block-paragraph\">Una de las preocupaciones m\u00e1s controvertidas que afectan a los seres humanos, y que nos planteamos frecuentemente es&nbsp;\u00bfa d\u00f3nde vamos cuando morimos?&nbsp;Es un enigma milenario, puesto que la muerte a\u00fan golpea los sentimientos y es motivo de tortura para la inteligencia.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-3b06d7e2429a600edeb2623f103a0d4c wp-block-paragraph\">Hermes Trimegisto en \u201cEL KYBALION\u201d,&nbsp;el documento del Siglo XIX que resume las ense\u00f1anzas del hermetismo, afirmaba&nbsp;\u201ccomo es arriba, es abajo;&nbsp;como es abajo es arriba\u201d&nbsp;y que este principio se manifiesta en los tres Grandes Planos: el F\u00edsico, el Mental y el Espiritual.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-7cef53187b087923533fe43bfb96c84f wp-block-paragraph\">A lo largo de la historia de la humanidad todas las escuelas religiosas y filos\u00f3ficas han aportado una visi\u00f3n en relaci\u00f3n con su conocimiento, pero hemos de destacar que El Espiritismo dio comienzo al invalorable trabajo de demostrar la continuidad de la vida m\u00e1s all\u00e1 de la muerte, un fen\u00f3meno natural en el camino de la evoluci\u00f3n. M\u00faltiples esferas de la actividad espiritual tienen su complemento en los diversos sectores de la existencia. Las dimensiones vibratorias del universo son infinitas, como infinitos son los mundos que pueblan la inmensidad.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-6deb8a1a2c19e66adff914d7e6ae54a6 wp-block-paragraph\">Nadie muere. Las Colonias Espirituales se esparcen sobre toda la superficie del Planeta, construidas bajo los m\u00e1s variados motivos de sus fundadores.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-3ee91c7d43bcd5b95407b0b521294566 wp-block-paragraph\">Muchas personas se despiden del mundo carnal sin obst\u00e1culos y sin desagradables incidentes, otras duermen largu\u00edsimos sue\u00f1os y otras no perciben nada por su inconsciencia infantil que yace en sus expresiones.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-c07ab3013ee1d1eba63bd2f08500ec63 wp-block-paragraph\">Entre estos estados extremos, hay numerosos grados intermedios que permiten a los esp\u00edritus agruparse y constituir verdaderas sociedades espirituales. La comunidad de ideas y de sentimientos, la identidad de sus gustos, de opiniones y de aspiraciones atraen y unen a esas almas que forman grandes familias.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-8ee62f73b5414355bc1558bdf3921144 wp-block-paragraph\">La vida del Esp\u00edritu avanzado es esencialmente activa, aunque sin fatigas. Las distancias no existen para \u00e9l. Se desplaza con la rapidez del pensamiento. Su envoltura, es semejante a un vapor ligero que ha adquirido la sutilidad que es invisible para los Esp\u00edritus inferiores. Ve, oye, percibe, no ya con los \u00f3rganos materiales, que se interponen entre la Naturaleza y nosotros e interceptan el paso a la mayor parte de las sensaciones. Queda libre de todas las necesidades del cuerpo. La alimentaci\u00f3n y el sue\u00f1o no tienen para \u00e9l ninguna raz\u00f3n de ser. Al abandonar la Tierra, deja para siempre los vanos cuidados, todas las fantas\u00edas que envenenan la existencia terrenal. No necesitan de la palabra para comprenderse. El Esp\u00edritu puede salir de la Colonia, porque \u00e9l no se mantiene preso en ella. Siempre que est\u00e9 autorizado o acompa\u00f1ado, podr\u00e1 visitar a la familia.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-9af8a7dc517b038e675309dce7d58fb8 wp-block-paragraph\">Los Esp\u00edritus inferiores, sin embargo, llevan consigo, m\u00e1s all\u00e1 de la tumba, sus costumbres, sus necesidades sus preocupaciones materiales. No pudiendo elevarse por encima de la atm\u00f3sfera terrestre, vuelven a participar de la vida de los humanos, a intervenir en sus luchas, en sus trabajos y en sus placeres. Sus pasiones y sus apetitos, siempre vivos, les abruman, sobreexcitados por el continuo contacto con la humanidad y la imposibilidad de satisfacerlos supone para ellos una causa de tortura. Muchos de los liberados de la envoltura f\u00edsica, conservan tan fuerte afinidad con los intereses terrenales, que la vista no se les modifica de pronto, y prosiguen viviendo en la Tierra con las mismas expresiones con que la dejaron. Si resulta f\u00e1cil dejar el veh\u00edculo f\u00edsico, es muy dif\u00edcil abandonar la vieja morada del mundo. Los hilos morales son mucho m\u00e1s fuertes que las ligaduras de la carne.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-16d02a4b4706dcd7f8d25cd4aa1527cb wp-block-paragraph\">M\u00e1s, no todos los seres con alg\u00fan esclarecimiento, al desencarnar en la Tierra van a estas Colonias. Muchos van a otros planetas.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-6f56df5d2ec9a8bdc531d5736a78a305 wp-block-paragraph\">Despu\u00e9s de la muerte, antes de que el esp\u00edritu pueda orientarse, gravitando hacia el verdadero \u201chogar espiritual\u201d que le corresponde, siempre ser\u00e1 necesario que permanezca en una \u201cantec\u00e1mara\u201d en una regi\u00f3n cuya densidad y configuraciones aflictivas, en lo local, corresponder\u00e1n a los estados vibratorios y mentales del reci\u00e9n desencarnado. Se detendr\u00e1 ah\u00ed, hasta que sea naturalmente \u201cdes animalizado\u201d, es decir, hasta que se deshaga de los fluidos y de las fuerzas vitales de que se hallan impregnados todos los cuerpos materiales. Se comprende que la estancia en ese umbral del \u201cM\u00e1s All\u00e1\u201d, ser\u00e1 temporal, aunque generalmente penosa. Seg\u00fan haya sido el car\u00e1cter, las acciones practicadas, el g\u00e9nero de vida y el g\u00e9nero de muerte que haya tenido la entidad desencarnada, tal ser\u00e1 el tiempo y las penalidades que le esperan en el lugar descrito. Existen esp\u00edritus que apenas se demoran algunas horas, otros se quedar\u00e1n por meses o a\u00f1os consecutivos, regresando a la reencarnaci\u00f3n sin alcanzar la Espiritualidad.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-31c4d1e036fdc7b2fc764b596488c71f wp-block-paragraph\">Aparte de eso, hacemos notar que la sociedad del m\u00e1s all\u00e1 de la muerte, refleja los h\u00e1bitos a los que apeg\u00f3 en el mundo terrenal, por lo que los desencarnados de una ciudad asi\u00e1tica no se encuentran s\u00fabitamente con las costumbres y edificaciones de una ciudad occidental y viceversa.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-6867b58af09eb05f7e809b91ca28cc75 wp-block-paragraph\">Conocemos algunas de las m\u00e1s cercanas a la Tierra. Ellas disponen de calles, jardines, fuentes, hospitales, casas, medios de transporte, escuelas, ministerios, etc. Existen las mismas Leyes de la Gravedad que controlan la Tierra, con sus d\u00edas y sus noches, aunque las estaciones no tengan los rigores que en nuestro globo, ya que son suprimidos por factores de armon\u00eda existentes en las Colonias. Y esto ocurre, porque la mayor\u00eda de las Colonias que conocemos est\u00e1n circunscritas a la atm\u00f3sfera de la Tierra.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-72b03ba4872773ffcb9ec3fe5ecf32ce wp-block-paragraph\">Allan Kardec, el memorable Codificador, se refiere en varias oportunidades, en su obra, a la erraticidad, estado en el que se encuentra un considerable n\u00famero de seres humanos desencarnados, a la espera de una nueva reencarnaci\u00f3n.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-4a771abddeb57069cf47cbcbcea6fdc7 wp-block-paragraph\">La descripci\u00f3n de las distintas Colonias Espirituales y sus ambientes es mucho m\u00e1s lo que a d\u00eda de hoy nos es desconocido, que lo conocido.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-8321c12a193b77c48d05d0575991dcfb wp-block-paragraph\">Los seres del espacio, a trav\u00e9s de distintas mediumnidades, han venido descorriendo m\u00e1s y m\u00e1s el velo que nos oculta la vida en el&nbsp;M\u00e1s All\u00e1,&nbsp;mediante una serie notabil\u00edsima de obras mediumnicas, que han abierto la cortina, permitiendo ir conociendo como se desarrolla la vida de las almas en las esferas espirituales que circundan el planeta Tierra. Entre todas ellas destacamos:<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-dc830c05329c667582ceccfbbd03b8bc wp-block-paragraph\">La&nbsp;\u201cColonia Socorrista de Moradia\u201d,&nbsp;una de las m\u00e1s antiguas, que est\u00e1 dedicada a la atenci\u00f3n de la poblaci\u00f3n en el Umbral.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-32e6080addd7bf1fbf35989dfcaa2c82 wp-block-paragraph\">La&nbsp;\u201cColonia Campo de Paz\u201d,&nbsp;de la cual habla el Esp\u00edritu Andr\u00e9 Lu\u00edz en&nbsp;\u201cLos&nbsp;Mensajeros\u201d,&nbsp;est\u00e1 situada muy cerca de la Tierra.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-56929b60f44f0aca909885a5e553b632 wp-block-paragraph\">\u201cLa Casa Transitoria de Fabiano\u201d,&nbsp;es de asistencia a los desencarnados, citada en el libro&nbsp;\u201cObreros de la Vida Eterna\u201d.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-5c62c4db55bec2ae0e964483128dc43d wp-block-paragraph\">La&nbsp;\u201cColonia redenci\u00f3n\u201d,&nbsp;citada en el libro&nbsp;\u201cM\u00e1s all\u00e1 de la Muerte\u201d,&nbsp;descrita por Otilio Gonsalves, la&nbsp;\u201cColonia de la M\u00fasica\u201d,&nbsp;la&nbsp;\u201cColonia de los Escritores\u201d,&nbsp;la&nbsp;\u201cColonia Gordemonio\u201d,&nbsp;habitada por Esp\u00edritus pervertidos y malhechores, y citada en el libro&nbsp;\u201cApenas una sombra de mujer\u201d&nbsp;etc.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-21a2a91cfc9a3efa2b9df00ead550426 wp-block-paragraph\">NUESTRO HOGAR,&nbsp;es una colonia transitoria consagrada al trabajo y al socorro espiritual. Posee actualmente m\u00e1s de un mill\u00f3n de habitantes.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-26b5c3e3f00c610e049c6eec6e49b0b5 wp-block-paragraph\">ALPHA 1,&nbsp;es una gigantesca ciudad espiritual, situada sobre la regi\u00f3n norte de Europa, acoge eminentes cient\u00edficos, estudiosos e investigadores que, un d\u00eda, habitaron nuestro planeta, y hoy all\u00ed se re\u00fanen, continuando sus estudios, perfeccionando teor\u00edas, con la finalidad de suplir los futuros avances que en sus posteriores reencarnaciones en la Tierra, les permitir\u00e1n traer, bajo la forma de descubrimientos cient\u00edficos, nuevos escalones para la evoluci\u00f3n de la tecnolog\u00eda del Hombre.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-12d3a15e9196afe82b464412746c9ac5 wp-block-paragraph\">Otra colonia muy conocida y muy bien detallada, y que dirige Cairbar Schutel es la de&nbsp;\u201cAlborada Nueva\u201d,&nbsp;que est\u00e1 situada en la cuarta capa alrededor de la Tierra, por encima de la ciudad de Santos en el estado de Sao Paulo (Brasil). Es una ciudad espiritual con cerca de 200.000 habitantes, creada hace m\u00e1s tiempo que el de la mayor\u00eda de las colonias que permanecen en las zonas umbralinas.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-c893f51d09f84ab3b1b464efc27036fa wp-block-paragraph\">La m\u00e9dium brasile\u00f1a Vania Arantes Damo, nacida en Mote Alegre de Minas Gerais, nos relata en su libro&nbsp;\u201cMORADAS ESPIRITUALES\u201d,&nbsp;su experiencia, que gracias a la orientaci\u00f3n y acompa\u00f1amiento del Esp\u00edritu Juana Darque, durante el sue\u00f1o y con el apoyo de gu\u00edas espirituales viaj\u00f3 en el espacio en estado consciente. Algunas de estas colonias se describen con detalles d\u00e1ndonos una nueva perspectiva del mundo espiritual.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-7920c1a92945343cc42e2f9703663d91 wp-block-paragraph\">Destacamos entre las veinte colonias que cita en el libro, la&nbsp;\u201cColonia Morada del Sol\u201d,&nbsp;que se localiza en la parte oriental de Brasil, extendi\u00e9ndose desde el norte de Bah\u00eda, cerca de la ciudad de Altamira, atravesando Sergipe, pasando por Aracaju, sigue por Alagoas, v\u00eda Macel\u00f3, yendo hasta el Norte de Pernambuco, en la isla de Itamarac\u00e1. Es una colonia muy solicitada por su belleza y por proporcionar el fortalecimiento espiritual. La presencia del mar confiere serenidad al ambiente, contribuyendo al fortalecimiento de energ\u00edas que revitalizan el esp\u00edritu en su peregrinaci\u00f3n evolutiva.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-de27aa28206e04cda2d40c1449f8b8bf wp-block-paragraph\">Existen ciertas similitudes entre las Ciudades Espirituales cercanas a la Tierra, y las encontramos, desde las comunicaciones de Swedenborg, pasando por Andrew Jackson Davis, el Reverendo George Vale Owen, Raymond Lodge, Lester Coltman, Andr\u00e9 Luiz, el Esp\u00edritu Gregorio, que nos habl\u00f3 de Alpha 1, y Abel Glaser que recibi\u00f3 los informes de Cairbar Schutel, y Vania Arantes Damo, que nos detallaron los puntos de conexi\u00f3n que coinciden entre todas ellas.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-07b59583 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9eb6f805 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-5ff3bf3737c41168eb757c5b3b36bb29 wp-block-paragraph\"><em>Art\u00edculo redactado por Juan Miguel Fern\u00e1ndez<\/em><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-2cd209c1 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e0165dd0 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Las ciudades espirituales Una de las preocupaciones m\u00e1s controvertidas que afectan a los seres humanos, y que nos planteamos frecuentemente es&nbsp;\u00bfa d\u00f3nde vamos cuando morimos?&nbsp;Es un enigma milenario, puesto que la muerte a\u00fan golpea los sentimientos y es motivo de tortura para la inteligencia. Hermes Trimegisto en \u201cEL KYBALION\u201d,&nbsp;el documento del Siglo XIX que resume [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-6937","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v24.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las ciudades espirituales - Uni\u00f3n Esp\u00edrita<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nuevo-renacer.com\/it\/las-ciudades-espirituales\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las ciudades espirituales\" \/>\n<meta property=\"og:description\" content=\"Las ciudades espirituales Una de las preocupaciones m\u00e1s controvertidas que afectan a los seres humanos, y que nos planteamos frecuentemente es&nbsp;\u00bfa d\u00f3nde vamos cuando morimos?&nbsp;Es un enigma milenario, puesto que la muerte a\u00fan golpea los sentimientos y es motivo de tortura para la inteligencia. Hermes Trimegisto en \u201cEL KYBALION\u201d,&nbsp;el documento del Siglo XIX que resume [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nuevo-renacer.com\/it\/las-ciudades-espirituales\/\" \/>\n<meta property=\"og:site_name\" content=\"Uni\u00f3n Esp\u00edrita\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/3431398063740829\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-04T08:01:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2025\/02\/nosso-lar.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"392\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/\",\"url\":\"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/\",\"name\":\"Las ciudades espirituales - Uni\u00f3n Esp\u00edrita\",\"isPartOf\":{\"@id\":\"https:\/\/nuevo-renacer.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2025\/02\/nosso-lar.jpeg\",\"datePublished\":\"2025-02-04T07:16:17+00:00\",\"dateModified\":\"2025-02-04T08:01:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/#primaryimage\",\"url\":\"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2025\/02\/nosso-lar.jpeg\",\"contentUrl\":\"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2025\/02\/nosso-lar.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/nuevo-renacer.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las ciudades espirituales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nuevo-renacer.com\/#website\",\"url\":\"https:\/\/nuevo-renacer.com\/\",\"name\":\"Uni\u00f3n Esp\u00edrita\",\"description\":\"Nuevo Renacer\",\"publisher\":{\"@id\":\"https:\/\/nuevo-renacer.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nuevo-renacer.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nuevo-renacer.com\/#organization\",\"name\":\"UFEC\",\"url\":\"https:\/\/nuevo-renacer.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/nuevo-renacer.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-TERMINADO1-3-3.png\",\"contentUrl\":\"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-TERMINADO1-3-3.png\",\"width\":512,\"height\":512,\"caption\":\"UFEC\"},\"image\":{\"@id\":\"https:\/\/nuevo-renacer.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/groups\/3431398063740829\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Las ciudades espirituales - Uni\u00f3n Esp\u00edrita","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nuevo-renacer.com\/it\/las-ciudades-espirituales\/","og_locale":"it_IT","og_type":"article","og_title":"Las ciudades espirituales","og_description":"Las ciudades espirituales Una de las preocupaciones m\u00e1s controvertidas que afectan a los seres humanos, y que nos planteamos frecuentemente es&nbsp;\u00bfa d\u00f3nde vamos cuando morimos?&nbsp;Es un enigma milenario, puesto que la muerte a\u00fan golpea los sentimientos y es motivo de tortura para la inteligencia. Hermes Trimegisto en \u201cEL KYBALION\u201d,&nbsp;el documento del Siglo XIX que resume [&hellip;]","og_url":"https:\/\/nuevo-renacer.com\/it\/las-ciudades-espirituales\/","og_site_name":"Uni\u00f3n Esp\u00edrita","article_publisher":"https:\/\/www.facebook.com\/groups\/3431398063740829","article_modified_time":"2025-02-04T08:01:18+00:00","og_image":[{"width":550,"height":392,"url":"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2025\/02\/nosso-lar.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/","url":"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/","name":"Las ciudades espirituales - Uni\u00f3n Esp\u00edrita","isPartOf":{"@id":"https:\/\/nuevo-renacer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/#primaryimage"},"image":{"@id":"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/#primaryimage"},"thumbnailUrl":"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2025\/02\/nosso-lar.jpeg","datePublished":"2025-02-04T07:16:17+00:00","dateModified":"2025-02-04T08:01:18+00:00","breadcrumb":{"@id":"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/#primaryimage","url":"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2025\/02\/nosso-lar.jpeg","contentUrl":"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2025\/02\/nosso-lar.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/nuevo-renacer.com\/las-ciudades-espirituales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/nuevo-renacer.com\/"},{"@type":"ListItem","position":2,"name":"Las ciudades espirituales"}]},{"@type":"WebSite","@id":"https:\/\/nuevo-renacer.com\/#website","url":"https:\/\/nuevo-renacer.com\/","name":"Uni\u00f3n Esp\u00edrita","description":"Nuevo Renacer","publisher":{"@id":"https:\/\/nuevo-renacer.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nuevo-renacer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nuevo-renacer.com\/#organization","name":"UFEC","url":"https:\/\/nuevo-renacer.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nuevo-renacer.com\/#\/schema\/logo\/image\/","url":"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-TERMINADO1-3-3.png","contentUrl":"https:\/\/nuevo-renacer.com\/wp-content\/uploads\/2024\/05\/cropped-LOGO-TERMINADO1-3-3.png","width":512,"height":512,"caption":"UFEC"},"image":{"@id":"https:\/\/nuevo-renacer.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/3431398063740829"]}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"adbv0","author_link":"https:\/\/nuevo-renacer.com\/it\/author\/adbv0\/"},"uagb_comment_info":0,"uagb_excerpt":"Las ciudades espirituales Una de las preocupaciones m\u00e1s controvertidas que afectan a los seres humanos, y que nos planteamos frecuentemente es&nbsp;\u00bfa d\u00f3nde vamos cuando morimos?&nbsp;Es un enigma milenario, puesto que la muerte a\u00fan golpea los sentimientos y es motivo de tortura para la inteligencia. Hermes Trimegisto en \u201cEL KYBALION\u201d,&nbsp;el documento del Siglo XIX que resume&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/nuevo-renacer.com\/it\/wp-json\/wp\/v2\/pages\/6937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuevo-renacer.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nuevo-renacer.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nuevo-renacer.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nuevo-renacer.com\/it\/wp-json\/wp\/v2\/comments?post=6937"}],"version-history":[{"count":6,"href":"https:\/\/nuevo-renacer.com\/it\/wp-json\/wp\/v2\/pages\/6937\/revisions"}],"predecessor-version":[{"id":6946,"href":"https:\/\/nuevo-renacer.com\/it\/wp-json\/wp\/v2\/pages\/6937\/revisions\/6946"}],"wp:attachment":[{"href":"https:\/\/nuevo-renacer.com\/it\/wp-json\/wp\/v2\/media?parent=6937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}